{"id":1102,"date":"2025-09-23T13:37:00","date_gmt":"2025-09-23T16:37:00","guid":{"rendered":"https:\/\/www.usal.edu.ar\/ingenieria\/?p=1102"},"modified":"2025-09-23T13:39:54","modified_gmt":"2025-09-23T16:39:54","slug":"clase-especial-en-planeamiento-ambiental-cultura-estetica-y-conciencia-ambiental","status":"publish","type":"post","link":"https:\/\/www.usal.edu.ar\/ingenieria\/clase-especial-en-planeamiento-ambiental-cultura-estetica-y-conciencia-ambiental\/","title":{"rendered":"Clase especial en Planeamiento Ambiental: Cultura, Est\u00e9tica y Conciencia Ambiental"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full has-custom-border is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.usal.edu.ar\/ingenieria\/wp-content\/uploads\/sites\/9\/2025\/09\/Nota-3-Foto-1.jpg\" alt=\"\" class=\"wp-image-1104\" style=\"border-width:2px;border-radius:30px\" srcset=\"https:\/\/www.usal.edu.ar\/ingenieria\/wp-content\/uploads\/sites\/9\/2025\/09\/Nota-3-Foto-1.jpg 1024w, https:\/\/www.usal.edu.ar\/ingenieria\/wp-content\/uploads\/sites\/9\/2025\/09\/Nota-3-Foto-1-300x225.jpg 300w, https:\/\/www.usal.edu.ar\/ingenieria\/wp-content\/uploads\/sites\/9\/2025\/09\/Nota-3-Foto-1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.usal.edu.ar\/ingenieria\/wp-content\/uploads\/sites\/9\/2025\/09\/Separador-1.png\" alt=\"\" class=\"wp-image-1095\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad fue organizada y acompa\u00f1ada por el Arq. EPU Marcelo Robutti, Profesor Titular e Investigador de la Facultad de Arte y Arquitectura, junto con la Elizabeth Moyano, quienes colaboraron en la preparaci\u00f3n de esta enriquecedora experiencia. La asistencia t\u00e9cnica estuvo a cargo del Sr. Juan Rivas, destac\u00e1ndose la impecable calidad del audio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado lunes 15, en el marco de la materia Planeamiento Ambiental, se desarroll\u00f3 una clase te\u00f3rica centrada en los aspectos culturales y est\u00e9ticos que determinan la construcci\u00f3n del territorio y su relaci\u00f3n con el ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante tres horas y media, se recorrieron distintos tramos de la historia universal, acompa\u00f1ados de pistas de audio y clips, desde las civilizaciones prehel\u00e9nicas hasta la contemporaneidad actual, marcada por los universos de datos, la crisis ambiental y la necesidad de una mayor conciencia ecol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada cont\u00f3 con la participaci\u00f3n de la arquitecta Mar\u00eda Laura P\u00e9rez de San Rom\u00e1n como profesora visitante. Especialista en Gesti\u00f3n Ambiental Metropolitana (FADU-UBA), San Rom\u00e1n posee una amplia trayectoria acad\u00e9mica como profesora titular de Arquitectura I a V en la FADU-UBA, jurado en concursos docentes en FADU-UBA y UNM, e invitada en diversas universidades, incluida la Universidad del Salvador. Adem\u00e1s, es socia de la consultora Zirma, donde coordina un equipo multidisciplinario que desarrolla estudios de contaminaci\u00f3n ambiental, impacto urbano y movilidad sostenible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este espacio de intercambio acad\u00e9mico reafirma el compromiso de la Facultad de Ingenier\u00eda con la formaci\u00f3n integral de sus estudiantes, integrando la mirada cultural y est\u00e9tica con la conciencia ambiental, y fortaleciendo as\u00ed el v\u00ednculo entre universidad, territorio y sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad fue organizada y acompa\u00f1ada por el Arq. EPU Marcelo Robutti, Profesor Titular e Investigador de la Facultad de Arte y Arquitectura, junto con la Elizabeth Moyano, quienes colaboraron en la preparaci\u00f3n de esta enriquecedora experiencia. La asistencia t\u00e9cnica estuvo a cargo del Sr. Juan Rivas, destac\u00e1ndose la impecable calidad del audio. El pasado [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":1104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/posts\/1102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/comments?post=1102"}],"version-history":[{"count":3,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/posts\/1102\/revisions"}],"predecessor-version":[{"id":1107,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/posts\/1102\/revisions\/1107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/media\/1104"}],"wp:attachment":[{"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/media?parent=1102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/categories?post=1102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingenieria\/wp-json\/wp\/v2\/tags?post=1102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}