{"id":238,"date":"2023-09-15T17:22:24","date_gmt":"2023-09-15T15:22:24","guid":{"rendered":"https:\/\/www.usal.edu.ar\/ingreso\/?post_type=propuesta&#038;p=238"},"modified":"2025-11-18T15:35:31","modified_gmt":"2025-11-18T18:35:31","slug":"licenciatura-en-comercializacion","status":"publish","type":"propuesta","link":"https:\/\/www.usal.edu.ar\/ingreso\/propuesta\/licenciatura-en-comercializacion\/","title":{"rendered":"Licenciatura en Comercializaci\u00f3n"},"featured_media":34081,"template":"","meta":{"_acf_changed":false,"_uag_custom_page_level_css":""},"class_list":["post-238","propuesta","type-propuesta","status-publish","has-post-thumbnail","hentry"],"acf":{"unidad":{"simple_value_formatted":"<a class=\"post-link\" href=\"https:\/\/www.usal.edu.ar\/ingreso\/unidad\/facultad-de-ciencias-economicas-y-empresariales\/\" rel=\"bookmark\">Facultad de Ciencias Econ\u00f3micas y Empresariales<\/a>","value_formatted":123,"value":"123","field":{"ID":61,"key":"field_64bc256cb1f2e","label":"Unidad Acad\u00e9mica","name":"unidad","aria-label":"","prefix":"acf","type":"post_object","value":null,"menu_order":0,"instructions":"","required":1,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"post_type":["unidad"],"post_status":["publish"],"taxonomy":"","return_format":"id","multiple":0,"allow_null":0,"ui":1,"bidirectional_target":[],"_name":"unidad","_valid":1}},"tipo":{"simple_value_formatted":"<span class=\"value-item\">grado<\/span>","value_formatted":"grado","value":"grado","field":{"ID":28,"key":"field_64a0992b092c6","label":"Tipo de Propuesta","name":"tipo","aria-label":"","prefix":"acf","type":"select","value":null,"menu_order":1,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"30","class":"","id":""},"choices":{"grado":"Carrera de Grado","posgrado":"Posgrado","diplomatura":"Diplomatura","postitulo":"Post\u00edtulo","pregrado":"Pregrado"},"default_value":"grado","return_format":"value","multiple":0,"allow_null":0,"ui":0,"ajax":0,"placeholder":"","_name":"tipo","_valid":1,"create_options":0,"save_options":0}},"sedes":{"simple_value_formatted":"<ul><li><a class=\"post-link\" href=\"https:\/\/www.usal.edu.ar\/ingreso\/sede\/centro\/\" rel=\"bookmark\">Centro<\/a><\/li><li><a class=\"post-link\" href=\"https:\/\/www.usal.edu.ar\/ingreso\/sede\/pilar\/\" rel=\"bookmark\">Pilar<\/a><\/li><\/ul>","value_formatted":[77,94],"value":["77","94"],"field":{"ID":76,"key":"field_64bc2dc334376","label":"Sedes","name":"sedes","aria-label":"","prefix":"acf","type":"post_object","value":null,"menu_order":2,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"post_type":["sede"],"post_status":["publish"],"taxonomy":"","return_format":"object","multiple":1,"allow_null":0,"ui":1,"bidirectional_target":[],"_name":"sedes","_valid":1}},"se_cursa_en_rectorado":{"simple_value_formatted":"No","value_formatted":false,"value":0,"field":{"ID":22934,"key":"field_668d7dcf6be28","label":"Se cursa en Rectorado","name":"se_cursa_en_rectorado","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":3,"instructions":"","required":0,"id":"","class":"","conditional_logic":[[{"field":"field_64a0992b092c6","operator":"==","value":"posgrado"},{"field":"field_64bc2dc334376","operator":"==contains","value":"77"}]],"parent":22,"wrapper":{"width":"","class":"","id":""},"message":"Si est\u00e1 seleccionado, se mostrar\u00e1 la direcci\u00f3n de Rectorado como cursada para sede Centro.","default_value":0,"ui":0,"ui_on_text":"","ui_off_text":"","_name":"se_cursa_en_rectorado","_valid":1}},"a_distancia":{"simple_value_formatted":"No","value_formatted":false,"value":"0","field":{"ID":27,"key":"field_64a0986766d9f","label":"A distancia","name":"a_distancia","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":4,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"15","class":"","id":""},"message":"","default_value":0,"ui_on_text":"","ui_off_text":"","ui":1,"_name":"a_distancia","_valid":1}},"internacional":{"simple_value_formatted":"No","value_formatted":false,"value":"0","field":{"ID":29,"key":"field_64a09a0e61ef0","label":"Programa Internacional","name":"internacional","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":5,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"15","class":"","id":""},"message":"","default_value":0,"ui_on_text":"","ui_off_text":"","ui":1,"_name":"internacional","_valid":1}},"link":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":26,"key":"field_64a0982efd6f8","label":"Link externo","name":"link","aria-label":"","prefix":"acf","type":"url","value":null,"menu_order":6,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"50","class":"","id":""},"default_value":"","placeholder":"","_name":"link","_valid":1}},"orden":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":106,"key":"field_64bdbaf2a111d","label":"Orden","name":"orden","aria-label":"","prefix":"acf","type":"number","value":null,"menu_order":7,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","min":"","max":"","placeholder":"","step":"","prepend":"","append":"","_name":"orden","_valid":1}},"activa":{"simple_value_formatted":"S\u00ed","value_formatted":true,"value":"1","field":{"ID":112,"key":"field_64bdbe77f5ee3","label":"Activa","name":"activa","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":8,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"message":"","default_value":1,"ui_on_text":"","ui_off_text":"","ui":1,"_name":"activa","_valid":1}},"titulo":{"simple_value_formatted":"Licenciado en Comercializaci\u00f3n \/ Licenciado en Comercializaci\u00f3n con Orientaci\u00f3n en Negocios Digitales","value_formatted":"Licenciado en Comercializaci\u00f3n \/ Licenciado en Comercializaci\u00f3n con Orientaci\u00f3n en Negocios Digitales","value":"Licenciado en Comercializaci\u00f3n \/ Licenciado en Comercializaci\u00f3n con Orientaci\u00f3n en Negocios Digitales","field":{"ID":574,"key":"field_6522289866c7a","label":"T\u00edtulo","name":"titulo","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":9,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"titulo","_valid":1}},"titulo_intermedio":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":610,"key":"field_653050bc3cfc4","label":"T\u00edtulo Intermedio","name":"titulo_intermedio","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":10,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"titulo_intermedio","_valid":1}},"duracion":{"simple_value_formatted":"4 a\u00f1os","value_formatted":"4 a\u00f1os","value":"4 a\u00f1os","field":{"ID":575,"key":"field_652228e1f6397","label":"Duraci\u00f3n","name":"duracion","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":11,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"duracion","_valid":1}},"slogan":{"simple_value_formatted":"Gesti\u00f3n integral de la comercializaci\u00f3n en la era digital","value_formatted":"Gesti\u00f3n integral de la comercializaci\u00f3n en la era digital","value":"Gesti\u00f3n integral de la comercializaci\u00f3n en la era digital","field":{"ID":576,"key":"field_6522234f98e8f","label":"Slogan","name":"slogan","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":12,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"slogan","_valid":1}},"resumen":{"simple_value_formatted":"<p><span style=\"font-weight: 400\">El Licenciado en Comercializaci\u00f3n de la USAL podr\u00e1 incorporarse en diferentes \u00e1reas de una compa\u00f1\u00eda \u00edntimamente ligadas con el desarrollo del negocio: desde comercial, ventas o marketing hasta diferentes \u00e1reas de trabajo asociadas al desarrollo comercial, estrategias, investigaci\u00f3n de mercado, comunicaciones integradas, producto, administraci\u00f3n de negocios, publicidad, relaciones p\u00fablicas, branding todo en un marco de diferentes escenarios y envergaduras de negocios, tanto nacional como internacional.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La orientaci\u00f3n de negocios digitales de la carrera permite adem\u00e1s integrarse a una organizaci\u00f3n dentro de las \u00faltimas tendencias y realidades que es el marketing digital, la visi\u00f3n del negocio desde un punto de vista tecnol\u00f3gico, redes sociales, eCommerce, B2B, B2C y servicios financieros abriendo el campo a los trabajos que m\u00e1s requerimiento tienen en los \u00faltimos tiempos.<\/span><\/p>\n<table style=\"border-collapse: collapse;width: 100.817%;height: 225px\">\n<tbody>\n<tr style=\"height: 222px\">\n<td style=\"width: 7.94166%;height: 225px\">\n<p style=\"text-align: justify\">\u00a0<\/p>\n<\/td>\n<td style=\"width: 25.9318%;height: 225px\">\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43916 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB.png\" alt=\"\" width=\"1200\" height=\"512\" srcset=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB.png 1200w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB-300x128.png 300w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB-1024x437.png 1024w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB-768x328.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\">AACSB: Miembro de AACSB (Association to Advance Collegiate Schools of Business): Excelencia en Educaci\u00f3n Empresarial\u00bb<\/a><\/strong><\/p>\n<\/td>\n<td style=\"width: 10.697%;height: 225px\">\n<p>&nbsp;<\/p>\n<\/td>\n<td style=\"width: 23.0146%;height: 225px\">\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.praxismmt.com\/es\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-43917 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK.jpg\" alt=\"\" width=\"2250\" height=\"595\" srcset=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK.jpg 2250w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK-300x79.jpg 300w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK-1024x271.jpg 1024w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK-768x203.jpg 768w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK-1536x406.jpg 1536w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK-2048x542.jpg 2048w\" sizes=\"auto, (max-width: 2250px) 100vw, 2250px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.praxismmt.com\/es\/\">Simuladores: \u00abSimuladores de Negocios Praxis MMT: Innovaci\u00f3n en Formaci\u00f3n Empresarial\u00bb<\/a><\/strong><\/p>\n<\/td>\n<td style=\"width: 8.42793%;height: 225px\">\n<p style=\"text-align: justify\">\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table style=\"border-collapse: collapse;width: 100%;height: 109px\">\n<tbody>\n<tr style=\"height: 109px\">\n<td style=\"width: 42.3203%;height: 109px\">\u00a0<\/td>\n<td style=\"width: 20.098%;height: 109px\">\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.elibro.com\/index.php\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-46609 size-medium\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-300x102.png\" alt=\"\" width=\"300\" height=\"102\" srcset=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-300x102.png 300w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-1024x349.png 1024w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-768x262.png 768w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-1536x524.png 1536w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-2048x698.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.elibro.com\/index.php\">Biblioteca Digital Acad\u00e9mica<\/a><\/strong><\/p>\n<\/td>\n<td style=\"width: 37.5816%;height: 109px\">\u00a0<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","value_formatted":"<p><span style=\"font-weight: 400\">El Licenciado en Comercializaci\u00f3n de la USAL podr\u00e1 incorporarse en diferentes \u00e1reas de una compa\u00f1\u00eda \u00edntimamente ligadas con el desarrollo del negocio: desde comercial, ventas o marketing hasta diferentes \u00e1reas de trabajo asociadas al desarrollo comercial, estrategias, investigaci\u00f3n de mercado, comunicaciones integradas, producto, administraci\u00f3n de negocios, publicidad, relaciones p\u00fablicas, branding todo en un marco de diferentes escenarios y envergaduras de negocios, tanto nacional como internacional.<\/span><\/p>\r\n<p><span style=\"font-weight: 400\">La orientaci\u00f3n de negocios digitales de la carrera permite adem\u00e1s integrarse a una organizaci\u00f3n dentro de las \u00faltimas tendencias y realidades que es el marketing digital, la visi\u00f3n del negocio desde un punto de vista tecnol\u00f3gico, redes sociales, eCommerce, B2B, B2C y servicios financieros abriendo el campo a los trabajos que m\u00e1s requerimiento tienen en los \u00faltimos tiempos.<\/span><\/p>\r\n<table style=\"border-collapse: collapse;width: 100.817%;height: 225px\">\r\n<tbody>\r\n<tr style=\"height: 222px\">\r\n<td style=\"width: 7.94166%;height: 225px\">\r\n<p style=\"text-align: justify\">\u00a0<\/p>\r\n<\/td>\r\n<td style=\"width: 25.9318%;height: 225px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-43916 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB.png\" alt=\"\" width=\"1200\" height=\"512\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\">AACSB: Miembro de AACSB (Association to Advance Collegiate Schools of Business): Excelencia en Educaci\u00f3n Empresarial\"<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 10.697%;height: 225px\">\r\n<p>&nbsp;<\/p>\r\n<\/td>\r\n<td style=\"width: 23.0146%;height: 225px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.praxismmt.com\/es\/\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-43917 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK.jpg\" alt=\"\" width=\"2250\" height=\"595\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.praxismmt.com\/es\/\">Simuladores: \"Simuladores de Negocios Praxis MMT: Innovaci\u00f3n en Formaci\u00f3n Empresarial\"<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 8.42793%;height: 225px\">\r\n<p style=\"text-align: justify\">\u00a0<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<table style=\"border-collapse: collapse;width: 100%;height: 109px\">\r\n<tbody>\r\n<tr style=\"height: 109px\">\r\n<td style=\"width: 42.3203%;height: 109px\">\u00a0<\/td>\r\n<td style=\"width: 20.098%;height: 109px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.elibro.com\/index.php\" target=\"_blank\" rel=\"noopener\"><img class=\"wp-image-46609 size-medium\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-300x102.png\" alt=\"\" width=\"300\" height=\"102\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.elibro.com\/index.php\">Biblioteca Digital Acad\u00e9mica<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 37.5816%;height: 109px\">\u00a0<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<p>&nbsp;<\/p>","value":"<p><span style=\"font-weight: 400\">El Licenciado en Comercializaci\u00f3n de la USAL podr\u00e1 incorporarse en diferentes \u00e1reas de una compa\u00f1\u00eda \u00edntimamente ligadas con el desarrollo del negocio: desde comercial, ventas o marketing hasta diferentes \u00e1reas de trabajo asociadas al desarrollo comercial, estrategias, investigaci\u00f3n de mercado, comunicaciones integradas, producto, administraci\u00f3n de negocios, publicidad, relaciones p\u00fablicas, branding todo en un marco de diferentes escenarios y envergaduras de negocios, tanto nacional como internacional.<\/span><\/p>\r\n<p><span style=\"font-weight: 400\">La orientaci\u00f3n de negocios digitales de la carrera permite adem\u00e1s integrarse a una organizaci\u00f3n dentro de las \u00faltimas tendencias y realidades que es el marketing digital, la visi\u00f3n del negocio desde un punto de vista tecnol\u00f3gico, redes sociales, eCommerce, B2B, B2C y servicios financieros abriendo el campo a los trabajos que m\u00e1s requerimiento tienen en los \u00faltimos tiempos.<\/span><\/p>\r\n<table style=\"border-collapse: collapse;width: 100.817%;height: 225px\">\r\n<tbody>\r\n<tr style=\"height: 222px\">\r\n<td style=\"width: 7.94166%;height: 225px\">\r\n<p style=\"text-align: justify\">\u00a0<\/p>\r\n<\/td>\r\n<td style=\"width: 25.9318%;height: 225px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-43916 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/AACSB-logo-member-color-RGB.png\" alt=\"\" width=\"1200\" height=\"512\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.aacsb.edu\/\" target=\"_blank\" rel=\"noopener\">AACSB: Miembro de AACSB (Association to Advance Collegiate Schools of Business): Excelencia en Educaci\u00f3n Empresarial\"<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 10.697%;height: 225px\">\r\n<p>&nbsp;<\/p>\r\n<\/td>\r\n<td style=\"width: 23.0146%;height: 225px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.praxismmt.com\/es\/\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-43917 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/Logo-Praxis-MMT-Corp-CMYK.jpg\" alt=\"\" width=\"2250\" height=\"595\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.praxismmt.com\/es\/\">Simuladores: \"Simuladores de Negocios Praxis MMT: Innovaci\u00f3n en Formaci\u00f3n Empresarial\"<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 8.42793%;height: 225px\">\r\n<p style=\"text-align: justify\">\u00a0<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<table style=\"border-collapse: collapse;width: 100%;height: 109px\">\r\n<tbody>\r\n<tr style=\"height: 109px\">\r\n<td style=\"width: 42.3203%;height: 109px\">\u00a0<\/td>\r\n<td style=\"width: 20.098%;height: 109px\">\r\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.elibro.com\/index.php\" target=\"_blank\" rel=\"noopener\"><img class=\"wp-image-46609 size-medium\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/elibro-tag-300x102.png\" alt=\"\" width=\"300\" height=\"102\" \/><\/a><\/p>\r\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.elibro.com\/index.php\">Biblioteca Digital Acad\u00e9mica<\/a><\/strong><\/p>\r\n<\/td>\r\n<td style=\"width: 37.5816%;height: 109px\">\u00a0<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>\r\n<p>&nbsp;<\/p>","field":{"ID":577,"key":"field_6522237d98e90","label":"Resumen","name":"resumen","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":13,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":22,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"resumen","_valid":1}},"rr":{"simple_value_formatted":"R.R. N\u00b0 842\/19","value_formatted":"R.R. N\u00b0 842\/19","value":"R.R. N\u00b0 842\/19","field":{"ID":579,"key":"field_65259ae09ef15","label":"Resoluci\u00f3n Rectoral N\u00b0","name":"rr","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":0,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"rr","_valid":1}},"objetivos":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":580,"key":"field_65259ae09edf5","label":"Objetivos","name":"objetivos","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":1,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"objetivos","_valid":1}},"docentes":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":16835,"key":"field_660ad1de1e481","label":"Docentes","name":"docentes","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":2,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"docentes","_valid":1}},"perfil":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":16839,"key":"field_660ad6e0ab6db","label":"Perfil","name":"perfil","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":3,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"perfil","_valid":1}},"tesis":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":16837,"key":"field_660ad4be1c515","label":"Tesis","name":"tesis","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":4,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"tesis","_valid":1}},"horarios":{"simple_value_formatted":"<p><b>Sede Centro<\/b><\/p>\n<p><strong>Horario de clases: <\/strong><\/p>\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 8.00 a 12.00<\/p>\n<p>S\u00c1BADOS DE 9.00 A 13.00<\/p>\n<p><strong><em>Turno Noche:<\/em><\/strong> LUNES a VIERNES 19.00 a 23.00<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes y s\u00e1bados se llevan a cabo en modalidad virtual.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><b>Delegaci\u00f3n Pilar &#8211; Campus \u201cNtra. Sra. del Pilar\u201d<\/b><\/p>\n<p><strong>Horario de clases:<\/strong><\/p>\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 9.00 a 13.00<\/p>\n<p><strong><em>Turno Noche: <\/em><\/strong>LUNES a VIERNES 17.30 a 21.30<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes se llevan a cabo en modalidad virtual.<\/p>\n","value_formatted":"<p><b>Sede Centro<\/b><\/p>\r\n<p><strong>Horario de clases: <\/strong><\/p>\r\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 8.00 a 12.00<\/p>\r\n<p>S\u00c1BADOS DE 9.00 A 13.00<\/p>\r\n<p><strong><em>Turno Noche:<\/em><\/strong> LUNES a VIERNES 19.00 a 23.00<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes y s\u00e1bados se llevan a cabo en modalidad virtual.<\/p>\r\n<p>&nbsp;<\/p>\r\n<hr \/>\r\n<p><b>Delegaci\u00f3n Pilar - Campus \u201cNtra. Sra. del Pilar\u201d<\/b><\/p>\r\n<p><strong>Horario de clases:<\/strong><\/p>\r\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 9.00 a 13.00<\/p>\r\n<p><strong><em>Turno Noche: <\/em><\/strong>LUNES a VIERNES 17.30 a 21.30<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes se llevan a cabo en modalidad virtual.<\/p>","value":"<p><b>Sede Centro<\/b><\/p>\r\n<p><strong>Horario de clases: <\/strong><\/p>\r\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 8.00 a 12.00<\/p>\r\n<p>S\u00c1BADOS DE 9.00 A 13.00<\/p>\r\n<p><strong><em>Turno Noche:<\/em><\/strong> LUNES a VIERNES 19.00 a 23.00<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes y s\u00e1bados se llevan a cabo en modalidad virtual.<\/p>\r\n<p>&nbsp;<\/p>\r\n<hr \/>\r\n<p><b>Delegaci\u00f3n Pilar - Campus \u201cNtra. Sra. del Pilar\u201d<\/b><\/p>\r\n<p><strong>Horario de clases:<\/strong><\/p>\r\n<p><strong><em>Turno Ma\u00f1ana:<\/em><\/strong> LUNES a VIERNES 9.00 a 13.00<\/p>\r\n<p><strong><em>Turno Noche: <\/em><\/strong>LUNES a VIERNES 17.30 a 21.30<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>Observaciones:<\/strong> 3\u00b0 y 4\u00ba a\u00f1o solo se cursa en el turno noche. Las materias que se cursan los d\u00edas viernes se llevan a cabo en modalidad virtual.<\/p>","field":{"ID":2182,"key":"field_655f3d73f0e1b","label":"Horarios","name":"horarios","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":5,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"horarios","_valid":1}},"ingreso":{"simple_value_formatted":"<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2025-<\/strong><\/p>\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\n<p><strong>Fecha<\/strong>: Entre el 15\/08\/2025 y el 31\/10\/2025<\/p>\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>-INGRESO CICLO LECTIVO 2026-<\/strong><\/p>\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\n<p><strong>Fecha<\/strong>: Entre el 16\/02\/2026 y el 30\/04\/2026<\/p>\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2026-<\/strong><\/p>\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\n<p><strong>Fecha<\/strong>: Entre el 18\/08\/2026 y el 30\/10\/2026<\/p>\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\n","value_formatted":"<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2025-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 15\/08\/2025 y el 31\/10\/2025<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>-INGRESO CICLO LECTIVO 2026-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 16\/02\/2026 y el 30\/04\/2026<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2026-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 18\/08\/2026 y el 30\/10\/2026<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>","value":"<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2025-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 15\/08\/2025 y el 31\/10\/2025<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>-INGRESO CICLO LECTIVO 2026-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 16\/02\/2026 y el 30\/04\/2026<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>\r\n<p>&nbsp;<\/p>\r\n<p><strong>-INGRESO SEGUNDO CUATRIMESTRE 2026-<\/strong><\/p>\r\n<p><strong>CURSO DE NIVELACI\u00d3N VIRTUAL ON LINE<\/strong><\/p>\r\n<p><strong>Fecha<\/strong>: Entre el 18\/08\/2026 y el 30\/10\/2026<\/p>\r\n<p><strong>Modalidad:<\/strong> Virtual \/ Asincr\u00f3nico<\/p>\r\n<p>Se encuentran exceptuados los ingresantes con equivalencias externas y aquellos que posean ingreso directo por Convenio con los Colegios Secundarios.<\/p>\r\n<p><strong>Asignaturas:<\/strong> Matem\u00e1tica, Lenguaje Cient\u00edfico y Universitario<\/p>\r\n<p><strong>R\u00e9gimen de evaluaci\u00f3n y selecci\u00f3n:<\/strong> No vinculante al ingreso.<\/p>","field":{"ID":581,"key":"field_6526b0b572a89","label":"Informaci\u00f3n de Ingreso","name":"ingreso","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":6,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"ingreso","_valid":1}},"incluir_informacion_comun_ingreso":{"simple_value_formatted":"No","value_formatted":false,"value":"0","field":{"ID":684,"key":"field_653a95dd2cf42","label":"Incluir informaci\u00f3n com\u00fan de Ingreso","name":"incluir_informacion_comun_ingreso","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":7,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"message":"Si est\u00e1 seleccionado, incluye el contenido de la p\u00e1gina \"informacion-comun-de-ingreso\" (en caso de existir)","default_value":0,"ui":0,"ui_on_text":"","ui_off_text":"","_name":"incluir_informacion_comun_ingreso","_valid":1}},"plan":{"simple_value_formatted":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3093 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01.png\" alt=\"\" width=\"1891\" height=\"1899\" srcset=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01.png 1891w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01-300x300.png 300w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01-1020x1024.png 1020w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01-150x150.png 150w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01-768x771.png 768w, https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01-1530x1536.png 1530w\" sizes=\"auto, (max-width: 1891px) 100vw, 1891px\" \/><\/p>\n","value_formatted":"<p><img class=\"aligncenter wp-image-3093 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01.png\" alt=\"\" width=\"1891\" height=\"1899\" \/><\/p>","value":"<p><img class=\"aligncenter wp-image-3093 size-full\" src=\"https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/FolletoGradoComercializacionNegociosDigitales-01.png\" alt=\"\" width=\"1891\" height=\"1899\" \/><\/p>","field":{"ID":582,"key":"field_65259ae09ee2d","label":"Plan de Estudios","name":"plan","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":8,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"plan","_valid":1}},"coneau":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":583,"key":"field_65259ae09ee66","label":"CONEAU","name":"coneau","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":9,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"coneau","_valid":1}},"resolucion_ministerio":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":17603,"key":"field_661d9b810f4b0","label":"Resoluci\u00f3n Ministerial","name":"resolucion_ministerio","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":10,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"resolucion_ministerio","_valid":1}},"cpu_titulo":{"simple_value_formatted":"Profesor en Comercializaci\u00f3n","value_formatted":"Profesor en Comercializaci\u00f3n","value":"Profesor en Comercializaci\u00f3n","field":{"ID":584,"key":"field_6526b14472a8a","label":"CPU T\u00edtulo","name":"cpu_titulo","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":11,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"cpu_titulo","_valid":1}},"cpu_info":{"simple_value_formatted":"<p><i><span style=\"font-weight: 400\">Cursando y aprobando el Ciclo Pedag\u00f3gico en la Facultad de Ciencias de la Educaci\u00f3n y la Comunicaci\u00f3n Social se puede obtener el t\u00edtulo de Profesor en Comercializaci\u00f3n.<\/span><\/i><\/p>\n","value_formatted":"<p><i><span style=\"font-weight: 400\">Cursando y aprobando el Ciclo Pedag\u00f3gico en la Facultad de Ciencias de la Educaci\u00f3n y la Comunicaci\u00f3n Social se puede obtener el t\u00edtulo de Profesor en Comercializaci\u00f3n.<\/span><\/i><\/p>","value":"<p><i><span style=\"font-weight: 400\">Cursando y aprobando el Ciclo Pedag\u00f3gico en la Facultad de Ciencias de la Educaci\u00f3n y la Comunicaci\u00f3n Social se puede obtener el t\u00edtulo de Profesor en Comercializaci\u00f3n.<\/span><\/i><\/p>","field":{"ID":585,"key":"field_6526b17772a8c","label":"CPU Info","name":"cpu_info","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":12,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"cpu_info","_valid":1}},"inicio_ciclo":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":17605,"key":"field_661d9cfc0f4b2","label":"Inicio de ciclo","name":"inicio_ciclo","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":13,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"inicio_ciclo","_valid":1}},"cierre_inscripcion":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":17606,"key":"field_661d9d110f4b3","label":"Cierre de inscripcion","name":"cierre_inscripcion","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":14,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"cierre_inscripcion","_valid":1}},"aranceles":{"simple_value_formatted":"<table style=\"width: 610px\">\n<tbody>\n<tr>\n<td style=\"width: 610px\">\n<p><b>ARANCELES &#8211; Ingreso 2026 (Sujeto a modificaci\u00f3n)<\/b><\/p>\n<p><i>Los importes percibidos en concepto de Inscripci\u00f3n y Matricula no tienen devoluci\u00f3n<\/i><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 610px\">\n<p><strong>\u00a0Derecho de Inscripci\u00f3n:<\/strong> $ 130.000<\/p>\n<p><b>\u00a0Matr\u00edcula 2026: <\/b>Matr\u00edcula Adelantada $ 803.005 (Vto. 22\/12\/2025) o 3 cuotas de: $ 307.818 (vto. 1\u00ba cuota: 20\/01\/2026 \u2013 2\u00ba cuota: 10\/02\/2026 \u2013 3\u00aa cuota: 10\/03\/2026)<\/p>\n<p><strong>\u00a011<\/strong><b>\u00a0cuotas mensuales <\/b>(febrero a diciembre)<b> de:<\/b> $ [arancel]\u00a0<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","value_formatted":"<table style=\"width: 610px\">\r\n<tbody>\r\n<tr>\r\n<td style=\"width: 610px\">\r\n<p><b>ARANCELES - Ingreso 2026 (Sujeto a modificaci\u00f3n)<\/b><\/p>\r\n<p><i>Los importes percibidos en concepto de Inscripci\u00f3n y Matricula no tienen devoluci\u00f3n<\/i><\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"width: 610px\">\r\n<p><strong>\u00a0Derecho de Inscripci\u00f3n:<\/strong> $ 130.000<\/p>\r\n<p><b>\u00a0Matr\u00edcula 2026: <\/b>Matr\u00edcula Adelantada $ 803.005 (Vto. 22\/12\/2025) o 3 cuotas de: $ 307.818 (vto. 1\u00ba cuota: 20\/01\/2026 \u2013 2\u00ba cuota: 10\/02\/2026 \u2013 3\u00aa cuota: 10\/03\/2026)<\/p>\r\n<p><strong>\u00a011<\/strong><b>\u00a0cuotas mensuales <\/b>(febrero a diciembre)<b> de:<\/b> $ [arancel]\u00a0<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","value":"<table style=\"width: 610px\">\r\n<tbody>\r\n<tr>\r\n<td style=\"width: 610px\">\r\n<p><b>ARANCELES - Ingreso 2026 (Sujeto a modificaci\u00f3n)<\/b><\/p>\r\n<p><i>Los importes percibidos en concepto de Inscripci\u00f3n y Matricula no tienen devoluci\u00f3n<\/i><\/p>\r\n<\/td>\r\n<\/tr>\r\n<tr>\r\n<td style=\"width: 610px\">\r\n<p><strong>\u00a0Derecho de Inscripci\u00f3n:<\/strong> $ 130.000<\/p>\r\n<p><b>\u00a0Matr\u00edcula 2026: <\/b>Matr\u00edcula Adelantada $ 803.005 (Vto. 22\/12\/2025) o 3 cuotas de: $ 307.818 (vto. 1\u00ba cuota: 20\/01\/2026 \u2013 2\u00ba cuota: 10\/02\/2026 \u2013 3\u00aa cuota: 10\/03\/2026)<\/p>\r\n<p><strong>\u00a011<\/strong><b>\u00a0cuotas mensuales <\/b>(febrero a diciembre)<b> de:<\/b> $ [arancel]\u00a0<\/p>\r\n<\/td>\r\n<\/tr>\r\n<\/tbody>\r\n<\/table>","field":{"ID":2189,"key":"field_655fb96fa62c5","label":"Informaci\u00f3n de Aranceles","name":"aranceles","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":15,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"aranceles","_valid":1}},"arancel":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":586,"key":"field_65259ae09ecdc","label":"Arancel","name":"arancel","aria-label":"","prefix":"acf","type":"number","value":null,"menu_order":16,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","min":"","max":"","placeholder":"","step":"","prepend":"$","append":"","_name":"arancel","_valid":1}},"incluir_informacion_comun_aranceles":{"simple_value_formatted":"No","value_formatted":false,"value":"0","field":{"ID":2190,"key":"field_655fb992a62c6","label":"Incluir informaci\u00f3n com\u00fan de Aranceles","name":"incluir_informacion_comun_aranceles","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":17,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"message":"Si est\u00e1 seleccionado, incluye el contenido de la p\u00e1gina \"informacion-comun-de-aranceles\" (en caso de existir)","default_value":0,"ui":0,"ui_on_text":"","ui_off_text":"","_name":"incluir_informacion_comun_aranceles","_valid":1}},"director":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":17604,"key":"field_661d9be30f4b1","label":"Director","name":"director","aria-label":"","prefix":"acf","type":"text","value":null,"menu_order":19,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","maxlength":"","placeholder":"","prepend":"","append":"","_name":"director","_valid":1}},"mail":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":2200,"key":"field_6560ed6b8e31f","label":"Mail de contacto","name":"mail","aria-label":"","prefix":"acf","type":"email","value":null,"menu_order":20,"instructions":"Mail de contacto espec\u00edfico para la propuesta","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","placeholder":"","prepend":"","append":"","_name":"mail","_valid":1}},"id_interno":{"simple_value_formatted":1813,"value_formatted":1813,"value":"1813","field":{"ID":609,"key":"field_65305068c1c8a","label":"ID Carrera","name":"id_interno","aria-label":"","prefix":"acf","type":"number","value":null,"menu_order":21,"instructions":"ID interno de la carrera en los sistemas USAL. Por ej. 101 para Abogac\u00eda, 401 para Medicina","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","min":"","max":"","placeholder":"","step":"","prepend":"","append":"","_name":"id_interno","_valid":1}},"otros":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":587,"key":"field_65259ae09ef4e","label":"Otros","name":"otros","aria-label":"","prefix":"acf","type":"wysiwyg","value":null,"menu_order":22,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"default_value":"","tabs":"all","toolbar":"full","media_upload":0,"delay":0,"_name":"otros","_valid":1}},"superponer_nombre":{"simple_value_formatted":"S\u00ed","value_formatted":true,"value":"1","field":{"ID":622,"key":"field_6531808c3c9ba","label":"Superponer nombre de Unidad","name":"superponer_nombre","aria-label":"","prefix":"acf","type":"true_false","value":null,"menu_order":23,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"message":"Sobreponer Nombre de la Unidad en Imagen del Encabezado","default_value":1,"ui":0,"ui_on_text":"","ui_off_text":"","_name":"superponer_nombre","_valid":1}},"folleto":{"simple_value_formatted":"","value_formatted":"","value":"","field":{"ID":27052,"key":"field_66c79966163fd","label":"Folleto","name":"folleto","aria-label":"","prefix":"acf","type":"file","value":null,"menu_order":23,"instructions":"","required":0,"id":"","class":"","conditional_logic":0,"parent":578,"wrapper":{"width":"","class":"","id":""},"return_format":"array","library":"all","min_size":"","max_size":"","mime_types":"pdf","_name":"folleto","_valid":1}}},"mb":[],"uagb_featured_image_src":{"full":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01.png",1920,480,false],"thumbnail":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01-150x150.png",150,150,true],"medium":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01-300x75.png",300,75,true],"medium_large":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01-768x192.png",768,192,true],"large":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01-1024x256.png",1024,256,true],"1536x1536":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01-1536x384.png",1536,384,true],"2048x2048":["https:\/\/www.usal.edu.ar\/ingreso\/wp-content\/uploads\/sites\/2\/2023\/09\/IlustracionComercializacionNegociosDigitales-01.png",1920,480,false]},"uagb_author_info":{"display_name":"Mat\u00edas Saettone","author_link":"https:\/\/www.usal.edu.ar\/ingreso\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"mfb_rest_fields":["title","uagb_featured_image_src","uagb_author_info","uagb_comment_info","uagb_excerpt"],"_links":{"self":[{"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/propuesta\/238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/propuesta"}],"about":[{"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/types\/propuesta"}],"version-history":[{"count":24,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/propuesta\/238\/revisions"}],"predecessor-version":[{"id":53253,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/propuesta\/238\/revisions\/53253"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/sede\/94"},{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/sede\/77"},{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/unidad\/123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/media\/34081"}],"wp:attachment":[{"href":"https:\/\/www.usal.edu.ar\/ingreso\/wp-json\/wp\/v2\/media?parent=238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}